{"id":454150,"date":"2022-01-11T11:31:49","date_gmt":"2022-01-11T16:31:49","guid":{"rendered":"https:\/\/gijn.org\/?p=454150"},"modified":"2023-09-05T14:40:47","modified_gmt":"2023-09-05T18:40:47","slug":"herramientas-de-negocios-para-redacciones-recursos-audiovisuales","status":"publish","type":"post","link":"https:\/\/gijn.org\/es\/articulos\/herramientas-de-negocios-para-redacciones-recursos-audiovisuales\/","title":{"rendered":"Herramientas de negocios para redacciones: recursos audiovisuales"},"content":{"rendered":"<p><a href=\"https:\/\/gijn.org\/wp-content\/uploads\/2021\/08\/6-Chapter-Six-NO-Title.png\"><\/a><\/p>\n<p>Estas opciones te permitir\u00e1n grabar y editar, tanto audio como video, as\u00ed como integrarlos a tu sitio web para su f\u00e1cil difusi\u00f3n.<\/p>\n<p><b>Audio<\/b><\/p>\n<p><a rel=\"noopener\" target=\"_blank\" href=\"https:\/\/anchor.fm\/\"><b>Anchor<\/b><\/a><\/p>\n<p>Anchor es el servicio de hosting y distribuci\u00f3n de podcasts de Spotify. Ofrece espacio ilimitado para que los usuarios suban podcasts, automatiza su distribuci\u00f3n a la mayor\u00eda de las grandes plataformas y ofrece un an\u00e1lisis de las descargas, oyentes y estad\u00edsticas demogr\u00e1ficas de la audiencia del podcast. Adem\u00e1s, Anchor incluye herramientas de grabaci\u00f3n y edici\u00f3n b\u00e1sicas. De paso, le permite a los usuarios a\u00f1adir un bot\u00f3n para donaciones o \u201cpatrocinio\u201d para monetizar sus podcasts.<\/p>\n<p>Costo: gratis.<\/p>\n<p>Idiomas: ingl\u00e9s, espa\u00f1ol, franc\u00e9s, italiano, portugu\u00e9s, alem\u00e1n y sueco.<\/p>\n<p><a rel=\"noopener\" target=\"_blank\" href=\"https:\/\/www.audacityteam.org\/\"><b>Audacity<\/b><\/a><\/p>\n<p>Audacity es el software de audio gratuito m\u00e1s vers\u00e1til. Puede utilizarse para grabar y editar una gran variedad de formatos de audio y viene con varios efectos, incluyendo reducci\u00f3n de ruido. Su mayor desventaja es que su interfaz no es muy intuitiva, pero su popularidad y longevidad hacen que encontrar videos tutoriales en l\u00ednea sea f\u00e1cil.<\/p>\n<p>Costo: gratis.<\/p>\n<p>Idiomas: el software est\u00e1 disponible en m\u00e1s de 50 idiomas. El manual ha sido traducido a algunos.<\/p>\n<p><a rel=\"noopener\" target=\"_blank\" href=\"https:\/\/www.wooji-juice.com\/products\/ferrite\/\"><b>Ferrite Recording Studio<\/b><\/a><\/p>\n<p>Ferrite es una aplicaci\u00f3n para iPhone y iPad para grabar y editar m\u00faltiples pistas de audio. Est\u00e1 dise\u00f1ado para funcionar con audios de di\u00e1logo, no para m\u00fasica, e incluye un paquete completo de caracter\u00edsticas, como la posibilidad de marcar un momento o poner una etiqueta durante las grabaciones, que pueden ser \u00fatiles cuando se est\u00e1 grabando una entrevista larga que se planea editar o citar m\u00e1s adelante, adem\u00e1s de contar con ajustes autom\u00e1ticos de narraci\u00f3n.<\/p>\n<p>La versi\u00f3n gratuita incluye las caracter\u00edsticas b\u00e1sicas de la aplicaci\u00f3n, mientras que la de paga tiene m\u00e1s opciones de automatizaci\u00f3n, incluyendo un control de volumen autom\u00e1tico y la habilidad de guardar los ajustes o una plantilla si planeas grabar en el mismo lugar m\u00e1s de una vez.<\/p>\n<p>Costo: tiene una versi\u00f3n gratuita y una profesional que empieza en $14.99 d\u00f3lares.<\/p>\n<p>Idiomas: ingl\u00e9s.<\/p>\n<p><a rel=\"noopener\" target=\"_blank\" href=\"https:\/\/freemusicarchive.org\/\"><b>Free Music Archive<\/b><\/a><\/p>\n<p>Free Music Archive, que fue creado por la innovadora estaci\u00f3n de radio WFMU y m\u00e1s adelante se independiz\u00f3, es un archivo de m\u00fasica con licencia Creative Commons, que puede descargarse y utilizarse como tema principal para un podcast, como cortinillas o como m\u00fasica de fondo. Las canciones pueden buscarse por g\u00e9nero, artista, humor y m\u00e1s.<\/p>\n<p>Costo: la versi\u00f3n b\u00e1sica es gratuita. Los planes profesionales y sin royalty del socio de FMA, Tribe of Noise, son escalonados y tienen un coste inicial de 45\u20ac ($54 US) por canci\u00f3n, para cada proyecto.<\/p>\n<p>Idiomas: ingl\u00e9s.<\/p>\n<p><a rel=\"noopener\" target=\"_blank\" href=\"https:\/\/hindenburg.com\/products\/hindenburg-journalist-pro\"><b>Hindenburg Journalist<\/b><\/a><\/p>\n<p>Hindenburg Journalist ofrece una alternativa a ProTools f\u00e1cil de utilizar y dise\u00f1ada para el periodismo radial. Los usuarios pueden grabar en Hindenburg Journalist o editar audio pregrabado. Hindenburg le permite a sus usuarios organizar los diferentes clips que quieren editar seg\u00fan su tipo (por ejemplo, m\u00fasica de fondo, narraci\u00f3n o fragmentos de entrevistas) y, como caracter\u00edstica crucial, ajusta de manera autom\u00e1tica el volumen de los diferentes segmentos, asegur\u00e1ndose de que las din\u00e1micas est\u00e1n balanceadas en el resultado final. Adem\u00e1s, facilita la opci\u00f3n de publicar sus piezas en plataformas como SoundCloud.<\/p>\n<p>Costo: prueba gratis de 30 d\u00edas. $95 d\u00f3lares para un solo usuario. Contacta a la compa\u00f1\u00eda para obtener los precios para organizaciones. Hindenburg comenz\u00f3 como una herramienta para peque\u00f1os proyectos de radios comunitarias y ofrece descuentos a ONGs y proyectos de desarrollo medi\u00e1tico.<\/p>\n<p>Idiomas: ingl\u00e9s, checo, dan\u00e9s, finland\u00e9s, franc\u00e9s, alem\u00e1n, espa\u00f1ol y sueco.<\/p>\n<p><a rel=\"noopener\" target=\"_blank\" href=\"https:\/\/www.podbean.com\/\"><b>Podbean<\/b><\/a><\/p>\n<p>Podbean es una destacada plataforma de hosting y distribuci\u00f3n de podcasts. Su versi\u00f3n gratuita ofrece un conjunto limitado de funciones comparado con su plan pago, que permite subir cinco horas de audio y ofrece un ancho de banda mensual de 100GB. Podbean da facilidades de incrustar un reproductor de podcast en un sitio\u00a0 web y de crear una p\u00e1gina para promocionar sus audios. A los usuarios de la versi\u00f3n paga tambi\u00e9n les permite monetizar sus podcasts por medio de anuncios o crowdfundings.<\/p>\n<p>Costo: plan b\u00e1sico gratuito. Pago desde $9 d\u00f3lares al mes con almacenamiento y banda ancha ilimitados.<\/p>\n<p>Idiomas: ingl\u00e9s.<\/p>\n<p><a rel=\"noopener\" target=\"_blank\" href=\"https:\/\/soundcite.knightlab.com\/\"><b>Soundcite<\/b><\/a><\/p>\n<p>Soundcite es una herramienta financiada por Knight Lab de Northwestern University, que da la opci\u00f3n a los periodistas de incorporar fragmentos de audio directamente en un art\u00edculo escrito, en lugar de incrustar un enlace externo de YouTube o SoundCloud. Subes el archivo de audio al servidor de la p\u00e1gina web, seleccionas el fragmento del archivo que quieres que tus lectores escuchen mientras leen la pieza y se publica de manera autom\u00e1tica. Luce parecido a un enlace en el texto del art\u00edculo. Soundcite est\u00e1 disponible como complemento de WordPress.<\/p>\n<p>Costo: gratis.<\/p>\n<p>Idiomas: ingl\u00e9s.<\/p>\n<p><a rel=\"noopener\" target=\"_blank\" href=\"https:\/\/squadcast.fm\/\"><b>Squadcast<\/b><\/a><\/p>\n<p>Squadcast sirve para realizar entrevistas a distancia. Se graba a cada usuario por separado, lo que permite una edici\u00f3n m\u00e1s directa de la conversaci\u00f3n. Conforme se graba la entrevista, el archivo se sube a la nube de Squadcast, como respaldo adicional. Squadcast ofrece un archivo WAV (sin p\u00e9rdidas) y uno MP3 de todas las conversaciones e incluye algunas \u00fatiles funciones para resolver los problemas que suelen surgir al grabar entrevistas en l\u00ednea. Por ejemplo, los usuarios pueden ver qu\u00e9 equipo est\u00e1n utilizando los dem\u00e1s. Aunque las grabaciones son archivos de audio, los participantes tambi\u00e9n pueden encender sus c\u00e1maras durante la conversaci\u00f3n.<\/p>\n<p>Costo: el plan m\u00e1s barato cuesta $20 d\u00f3lares al mes con un periodo de prueba gratuito de 7 d\u00edas. Ofrece un descuento para organizaciones ben\u00e9ficas.<\/p>\n<p>Idiomas: ingl\u00e9s.<\/p>\n<p><a rel=\"noopener\" target=\"_blank\" href=\"https:\/\/zencastr.com\/\"><b>Zencastr<\/b><\/a><\/p>\n<p>Zencastr es una opci\u00f3n para grabar con facilidad una entrevista o conversaci\u00f3n a distancia. Al utilizar la herramienta, la llamada se realiza por medio de un VoIP, como una llamada de Zoom o de Skype. Al final de la conversaci\u00f3n, cada participante tiene un archivo con su parte. Un usuario puede combinar ambas piezas en una sola, sin la p\u00e9rdida de calidad que conlleva grabar con Zoom o Skype. Tambi\u00e9n cuenta con una herramienta similar para videos en fase de prueba.<\/p>\n<p>Costo: versi\u00f3n gratuita disponible (solo permite que los usuarios graben en MP3 y tienen que pagar para utilizar las herramientas de postproducci\u00f3n). El plan pago cuesta desde $20 d\u00f3lares al mes para grabaciones ilimitadas.<\/p>\n<p>Idiomas: ingl\u00e9s.<\/p>\n<p><b>Video<\/b><\/p>\n<p><a rel=\"noopener\" target=\"_blank\" href=\"https:\/\/www.blender.org\/\"><b>Blender<\/b><\/a><\/p>\n<p>El software de edici\u00f3n de Blender est\u00e1 pensado para que los usuarios modelen y exporten gr\u00e1ficos tanto en 3D como animaciones. Sin embargo, tambi\u00e9n incluye una funci\u00f3n de edici\u00f3n de video f\u00e1cil de utilizar y accesible para principiantes. Aunque las caracter\u00edsticas 3D pueden ser demasiado avanzadas para los usuarios sin experiencia, Blender se compara con otros softwares costosos para realizar las mismas funciones.<\/p>\n<p>Costo: gratis.<\/p>\n<p>Idioma: disponible en 36 idiomas.<\/p>\n<p><a rel=\"noopener\" target=\"_blank\" href=\"https:\/\/clipchamp.com\/es\/\"><b>ClipChamp<\/b><\/a><\/p>\n<p>ClimpChamp es un editor de video en l\u00ednea. Los usuarios pueden grabar con el micr\u00f3fono y c\u00e1mara de su computadora o subir videos, sonidos e im\u00e1genes; despu\u00e9s, utilizar las herramientas b\u00e1sicas de edici\u00f3n y la librer\u00eda de plantillas de ClipChamp para crear videos editados, presentaciones de diapositivas y GIFs.<\/p>\n<p>Costo: la versi\u00f3n gratuita permite a los usuarios exportar videos con resoluci\u00f3n de 480p y marca de agua. Los planes pagos ofrecen exportaciones de 720p desde $9 d\u00f3lares al mes.<\/p>\n<p>Idiomas: ingl\u00e9s, chino, espa\u00f1ol, franc\u00e9s, alem\u00e1n, indonesio, polaco, ruso, italiano, holand\u00e9s, dan\u00e9s, sueco, finland\u00e9s, noruego, coreano y japon\u00e9s.<\/p>\n<p><a rel=\"noopener\" target=\"_blank\" href=\"https:\/\/www.blackmagicdesign.com\/es\/products\/davinciresolve\/\"><b>DaVinci Resolve<\/b><\/a><\/p>\n<p>La versi\u00f3n gratuita que ofrece DaVinci Resolve de su software profesional de edici\u00f3n de video, correcci\u00f3n de color y efectos visuales cuenta con casi todas las funciones del programa. DaVinci Resolve no est\u00e1 dise\u00f1ado para principiantes, pero si alguien en la plantilla de una instituci\u00f3n tiene experiencia editando video, vale la pena probar este producto. Individuos de la industria cinematogr\u00e1fica han se\u00f1alado que algunas de las funciones gratuitas de DaVinci Resolve son m\u00e1s avanzadas que las de otros productos pagos.<\/p>\n<p>Costo: gratis.<\/p>\n<p>Idiomas: ingl\u00e9s, japon\u00e9s, chino, espa\u00f1ol, portugu\u00e9s y franc\u00e9s.<\/p>\n<p><a rel=\"noopener\" target=\"_blank\" href=\"https:\/\/www.kapwing.com\/\"><b>Kapwing<\/b><\/a><\/p>\n<p>Kapwing es un software de manipulaci\u00f3n de video e im\u00e1genes basado en la nube con una interfaz de usuario clara y sencilla, dise\u00f1ado para personas menos familiarizadas con la edici\u00f3n de video. Los usuarios pueden combinar varios videos en uno, a\u00f1adir subt\u00edtulos y audio, crear presentaciones de diapositivas o memes, cambiar el tama\u00f1o de im\u00e1genes y videos y publicar en redes sociales. Tiene aplicaciones para iOS y Android, lo cual lo hace una herramienta \u00fatil para periodistas que quieren editar o subir videos con rapidez mientras realizan trabajo de campo.<\/p>\n<p>Costo: la versi\u00f3n gratuita est\u00e1 disponible con limitaciones (m\u00e1ximo de 250 MB para subir videos). El plan pago es de $17 d\u00f3lares al mes para importar y exportar archivos m\u00e1s grandes y guardarlos en l\u00ednea m\u00e1s tiempo.<\/p>\n<p>Idiomas: ingl\u00e9s.<\/p>\n<p><a rel=\"noopener\" target=\"_blank\" href=\"https:\/\/shotcut.org\/\"><b>Shotcut<\/b><\/a><\/p>\n<p>Shotcut es un editor de video gratuito de c\u00f3digo abierto. Aunque tiene una interfaz menos elegante que los programas profesionales o para principiantes, PCMag lo describe como \u201cligeramente menos utilizable que las ofertas comerciales\u201d. El software funciona con un amplio rango de formatos de video y ofrece las funciones b\u00e1sicas que necesita un usuario para editar video. Por ejemplo, contiene menos transiciones y efectos. Como muchos productos FOSS, Shotcut cuenta con una documentaci\u00f3n extensa en varios lenguajes y muchos videos tutoriales que pueden encontrarse en YouTube.<\/p>\n<p>Costo: gratis.<\/p>\n<p>Idiomas: traducido en 33 idiomas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estas opciones te permitir\u00e1n grabar y editar, tanto audio como video, as\u00ed como integrarlos a tu sitio web para su f\u00e1cil difusi\u00f3n.<\/p>\n","protected":false},"author":3031154,"featured_media":374915,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"republication-tracker-tool-hide-widget":false,"footnotes":"","_tec_slr_enabled":"","_tec_slr_layout":""},"categories":[23188],"tags":[12670,1798,12668,12669,12654,2951,2325],"gijn_topic":[],"series":[],"gijn_language":[17790],"gijn_region":[],"class_list":["post-454150","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articulos","tag-audacity","tag-audio","tag-audiovisuales","tag-free-music","tag-guia-de-herramientas-para-redacciones","tag-podcast","tag-video","gijn_language-es-es"],"acf":[],"ticketed":false,"_links":{"self":[{"href":"https:\/\/gijn.org\/es\/wp-json\/wp\/v2\/posts\/454150","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gijn.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gijn.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gijn.org\/es\/wp-json\/wp\/v2\/users\/3031154"}],"replies":[{"embeddable":true,"href":"https:\/\/gijn.org\/es\/wp-json\/wp\/v2\/comments?post=454150"}],"version-history":[{"count":1,"href":"https:\/\/gijn.org\/es\/wp-json\/wp\/v2\/posts\/454150\/revisions"}],"predecessor-version":[{"id":1223174,"href":"https:\/\/gijn.org\/es\/wp-json\/wp\/v2\/posts\/454150\/revisions\/1223174"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gijn.org\/es\/wp-json\/wp\/v2\/media\/374915"}],"wp:attachment":[{"href":"https:\/\/gijn.org\/es\/wp-json\/wp\/v2\/media?parent=454150"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gijn.org\/es\/wp-json\/wp\/v2\/categories?post=454150"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gijn.org\/es\/wp-json\/wp\/v2\/tags?post=454150"},{"taxonomy":"gijn_topic","embeddable":true,"href":"https:\/\/gijn.org\/es\/wp-json\/wp\/v2\/gijn_topic?post=454150"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/gijn.org\/es\/wp-json\/wp\/v2\/series?post=454150"},{"taxonomy":"gijn_language","embeddable":true,"href":"https:\/\/gijn.org\/es\/wp-json\/wp\/v2\/gijn_language?post=454150"},{"taxonomy":"gijn_region","embeddable":true,"href":"https:\/\/gijn.org\/es\/wp-json\/wp\/v2\/gijn_region?post=454150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}